{"id":33667,"date":"2020-06-18T15:03:52","date_gmt":"2020-06-18T13:03:52","guid":{"rendered":"http:\/\/mula.es\/web\/?p=33667"},"modified":"2021-05-12T20:09:10","modified_gmt":"2021-05-12T18:09:10","slug":"sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias","status":"publish","type":"post","link":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/","title":{"rendered":"SANIDAD | Restablecimiento del Servicio de los Consultorios M\u00e9dicos en pedan\u00edas"},"content":{"rendered":"<p style=\"text-align: justify;\">Tras las gestiones realizadas por el Alcalde de Mula, Juan Jes\u00fas Moreno y la Concejala de Sanidad, Antonia Gabarr\u00f3n, con el Servicio Murciano de Salud para el restablecimiento de los servicios de los consultorios m\u00e9dicos en las pedan\u00edas del Municipio, desde El Excmo. Ayuntamiento de Mula se informa a los vecinos de las Mismas que, desde hoy, dichos consultorios est\u00e1n operativos en los horarios de consulta que a continuaci\u00f3n se relacionan:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Y\u00c9CHAR\n<ul>\n<li>Martes y Mi\u00e9rcoles de 12 a 15 horas.<\/li>\n<li>Viernes de 8 a 11 horas.<\/li>\n<\/ul>\n<\/li>\n<li>LA PUEBLA DE MULA\n<ul>\n<li>Lunes y Mi\u00e9rcoles de 12 a 15 horas.<\/li>\n<li>Jueves de 8 a 11 horas.<\/li>\n<\/ul>\n<\/li>\n<li>FUENTE LIBRILLA\n<ul>\n<li>Lunes, Mi\u00e9rcoles y Viernes de 8 a 11 horas.<\/li>\n<\/ul>\n<\/li>\n<li>CASAS NUEVAS\n<ul>\n<li>Lunes de 8 a 15 horas. (A\u00fan existiendo el seguimiento telef\u00f3nico habitual con todos los usuarios y pacientes, si se viese aumentado el n\u00famero de citas que requieran de atenci\u00f3n presencial, en esta pedan\u00eda, tambi\u00e9n, se pasar\u00eda consulta los jueves en horario por determinar)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Es importante recordar que solo ser\u00e1n atendidos aquellos usuarios con CITA PREVIA, adem\u00e1s de tener en cuenta el estricto cumplimiento de los par\u00e1metros sanitarios de seguridad establecidos por las autoridades, como son el uso de la mascarilla y el respeto de las distancia social de seguridad, entre otros.<\/p>\n<p style=\"text-align: justify;\">El Excmo. Ayuntamiento de Mula quiere agradecer el Servicio Murciano de Salud las gestiones realizadas para el restablecimiento de los servicios anteriormente mencionados.<\/p>\n<p style=\"text-align: justify;\">Dado que, actualmente, en cuanto a asuntos sanitarios se refiere, vivimos una situaci\u00f3n excepcional, cabe esperar que con el paso de los d\u00edas y la vuelta a la denominada nueva normalidad, se ir\u00e1n restableciendo los horarios habituales en los consultorios de referencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras las gestiones realizadas por el Alcalde de Mula, Juan Jes\u00fas Moreno y la Concejala de Sanidad, Antonia Gabarr\u00f3n, con el Servicio Murciano de Salud para el restablecimiento de los servicios de los consultorios m\u00e9dicos en las pedan\u00edas del Municipio, desde El Excmo. Ayuntamiento de Mula se informa a los vecinos de las Mismas que,  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":33512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[127,90],"tags":[],"class_list":["post-33667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alcalde","category-sanidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SANIDAD | Restablecimiento del Servicio de los Consultorios M\u00e9dicos en pedan\u00edas - Ayuntamiento de Mula<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SANIDAD | Restablecimiento del Servicio de los Consultorios M\u00e9dicos en pedan\u00edas - Ayuntamiento de Mula\" \/>\n<meta property=\"og:description\" content=\"Tras las gestiones realizadas por el Alcalde de Mula, Juan Jes\u00fas Moreno y la Concejala de Sanidad, Antonia Gabarr\u00f3n, con el Servicio Murciano de Salud para el restablecimiento de los servicios de los consultorios m\u00e9dicos en las pedan\u00edas del Municipio, desde El Excmo. Ayuntamiento de Mula se informa a los vecinos de las Mismas que, [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Mula\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-18T13:03:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-12T18:09:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg?fit=200%2C218&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"218\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AyuntamientMula\" \/>\n<meta name=\"twitter:site\" content=\"@AyuntamientMula\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/a0dbffe9f4a3ed4aaebedcfef02f71a1\"},\"headline\":\"SANIDAD | Restablecimiento del Servicio de los Consultorios M\u00e9dicos en pedan\u00edas\",\"datePublished\":\"2020-06-18T13:03:52+00:00\",\"dateModified\":\"2021-05-12T18:09:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/\"},\"wordCount\":297,\"image\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/escudo-cuadrado-e1591045058235.jpg\",\"articleSection\":[\"alcalde\",\"sanidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/\",\"name\":\"SANIDAD | Restablecimiento del Servicio de los Consultorios M\u00e9dicos en pedan\u00edas - Ayuntamiento de Mula\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/escudo-cuadrado-e1591045058235.jpg\",\"datePublished\":\"2020-06-18T13:03:52+00:00\",\"dateModified\":\"2021-05-12T18:09:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/a0dbffe9f4a3ed4aaebedcfef02f71a1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/escudo-cuadrado-e1591045058235.jpg\",\"contentUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/escudo-cuadrado-e1591045058235.jpg\",\"width\":200,\"height\":218},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mula.es\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SANIDAD | Restablecimiento del Servicio de los Consultorios M\u00e9dicos en pedan\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/\",\"name\":\"Ayuntamiento de Mula\",\"description\":\"P\u00e1gina web del Ayuntamiento de Mula (Regi\u00f3n de Murcia)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mula.es\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/a0dbffe9f4a3ed4aaebedcfef02f71a1\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5423b9cd77f4c7f89a124365a268866f9dfee038c17fe9e37afd92b5920d810e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5423b9cd77f4c7f89a124365a268866f9dfee038c17fe9e37afd92b5920d810e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5423b9cd77f4c7f89a124365a268866f9dfee038c17fe9e37afd92b5920d810e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Nam viverra euismod odio, gravida pellentesque urna varius vitae. Sed dui lorem, adipiscing in adipiscing et, interdum nec metus. Mauris ultricies, justo eu convallis placerat, felis enim ornare nisi, vitae mattis nulla ante id dui. Ut lectus purus, commodo et tincidunt vel, interdum sed lectus. Vestibulum adipiscing tempor nisi id elementi.\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/author\\\/jose-maria-boti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SANIDAD | Restablecimiento del Servicio de los Consultorios M\u00e9dicos en pedan\u00edas - Ayuntamiento de Mula","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/","og_locale":"es_ES","og_type":"article","og_title":"SANIDAD | Restablecimiento del Servicio de los Consultorios M\u00e9dicos en pedan\u00edas - Ayuntamiento de Mula","og_description":"Tras las gestiones realizadas por el Alcalde de Mula, Juan Jes\u00fas Moreno y la Concejala de Sanidad, Antonia Gabarr\u00f3n, con el Servicio Murciano de Salud para el restablecimiento de los servicios de los consultorios m\u00e9dicos en las pedan\u00edas del Municipio, desde El Excmo. Ayuntamiento de Mula se informa a los vecinos de las Mismas que, [...]","og_url":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/","og_site_name":"Ayuntamiento de Mula","article_published_time":"2020-06-18T13:03:52+00:00","article_modified_time":"2021-05-12T18:09:10+00:00","og_image":[{"width":200,"height":218,"url":"https:\/\/i0.wp.com\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg?fit=200%2C218&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@AyuntamientMula","twitter_site":"@AyuntamientMula","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/#article","isPartOf":{"@id":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/"},"author":{"name":"admin","@id":"https:\/\/mula.es\/web\/#\/schema\/person\/a0dbffe9f4a3ed4aaebedcfef02f71a1"},"headline":"SANIDAD | Restablecimiento del Servicio de los Consultorios M\u00e9dicos en pedan\u00edas","datePublished":"2020-06-18T13:03:52+00:00","dateModified":"2021-05-12T18:09:10+00:00","mainEntityOfPage":{"@id":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/"},"wordCount":297,"image":{"@id":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/#primaryimage"},"thumbnailUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","articleSection":["alcalde","sanidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/","url":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/","name":"SANIDAD | Restablecimiento del Servicio de los Consultorios M\u00e9dicos en pedan\u00edas - Ayuntamiento de Mula","isPartOf":{"@id":"https:\/\/mula.es\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/#primaryimage"},"image":{"@id":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/#primaryimage"},"thumbnailUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","datePublished":"2020-06-18T13:03:52+00:00","dateModified":"2021-05-12T18:09:10+00:00","author":{"@id":"https:\/\/mula.es\/web\/#\/schema\/person\/a0dbffe9f4a3ed4aaebedcfef02f71a1"},"breadcrumb":{"@id":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/#primaryimage","url":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","contentUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","width":200,"height":218},{"@type":"BreadcrumbList","@id":"https:\/\/mula.es\/web\/sanidad-restablecimiento-del-servicio-de-los-consultorios-medicos-en-pedanias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mula.es\/web\/"},{"@type":"ListItem","position":2,"name":"SANIDAD | Restablecimiento del Servicio de los Consultorios M\u00e9dicos en pedan\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/mula.es\/web\/#website","url":"https:\/\/mula.es\/web\/","name":"Ayuntamiento de Mula","description":"P\u00e1gina web del Ayuntamiento de Mula (Regi\u00f3n de Murcia)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mula.es\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mula.es\/web\/#\/schema\/person\/a0dbffe9f4a3ed4aaebedcfef02f71a1","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5423b9cd77f4c7f89a124365a268866f9dfee038c17fe9e37afd92b5920d810e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5423b9cd77f4c7f89a124365a268866f9dfee038c17fe9e37afd92b5920d810e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5423b9cd77f4c7f89a124365a268866f9dfee038c17fe9e37afd92b5920d810e?s=96&d=mm&r=g","caption":"admin"},"description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Nam viverra euismod odio, gravida pellentesque urna varius vitae. Sed dui lorem, adipiscing in adipiscing et, interdum nec metus. Mauris ultricies, justo eu convallis placerat, felis enim ornare nisi, vitae mattis nulla ante id dui. Ut lectus purus, commodo et tincidunt vel, interdum sed lectus. Vestibulum adipiscing tempor nisi id elementi.","url":"https:\/\/mula.es\/web\/author\/jose-maria-boti\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa9DMY-8L1","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/33667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/comments?post=33667"}],"version-history":[{"count":2,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/33667\/revisions"}],"predecessor-version":[{"id":33669,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/33667\/revisions\/33669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/media\/33512"}],"wp:attachment":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/media?parent=33667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/categories?post=33667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/tags?post=33667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}