{"id":41398,"date":"2021-07-13T13:55:38","date_gmt":"2021-07-13T11:55:38","guid":{"rendered":"https:\/\/mula.es\/web\/?p=41398"},"modified":"2021-07-13T13:55:38","modified_gmt":"2021-07-13T11:55:38","slug":"servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano","status":"publish","type":"post","link":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/","title":{"rendered":"SERVICIOS | El Ayuntamiento realiza nuevos trabajos de accesibilidad a las instalaciones de la piscina municipal de verano"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: justify;\">Se ha adaptado uno de los aseos, se ha instalado una puerta para acceder a la zona de piscinas y se ha adaptado la silla de acceso al agua para su uso en la piscina grande y la mediana<\/p>\n<p style=\"text-align: justify;\">El Ayuntamiento de Mula trabaja este verano en la mejora de las instalaciones de la piscina municipal apostando por la accesibilidad de espacios para todos los usuarios, principalmente para las personas con movilidad reducida.<\/p>\n<p style=\"text-align: justify;\">As\u00ed lo ha asegurado el titular de Servicios Municipales, Vicente L\u00f3pez, durante una visita a la piscina en la que ha estado acompa\u00f1ada por las concejales de Turismo y de Sanidad.<\/p>\n<p style=\"text-align: justify;\">Junto a las actuaciones que se han realizado en a\u00f1os anteriores para facilitar el ba\u00f1o a todos los usuarios, en este ejercicio se ha adaptado uno de los aseos, se ha instalado una puerta para acceder a la piscina y se ha adaptado la silla de acceso al agua para poder utilizarla tanto en la piscina grande como en la mediana.<\/p>\n<p style=\"text-align: justify;\">\u201cEs importante que todos los usuarios, sea cual sea su condici\u00f3n f\u00edsica puedan acceder a las instalaciones de la piscina de verano y disfrutar del ba\u00f1o y una correcta estancia. Es por este motivo por el que seguimos adaptando las instalaciones para que el servicio sea acorde a las necesidades de los usuarios\u201d, afirma L\u00f3pez.<\/p>\n<\/div><div class=\"fusion-image-carousel fusion-image-carousel-fixed fusion-image-carousel-1 fusion-carousel-border\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-bottom\" data-layout=\"carousel\" data-autoplay=\"no\" data-autoplayspeed=\"2500\" data-autoplaypause=\"no\" data-loop=\"yes\" data-columns=\"2\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"13\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-freemode=\"no\" data-imagesize=\"fixed\" data-scrollitems=\"0\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-columns:2;--awb-border-width:1px;--awb-border-color:#e9eaee;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a href=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas2.jpg\" target=\"_self\"><img decoding=\"async\" width=\"460\" height=\"295\" src=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas2-460x295.jpg\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" data-attachment-id=\"41399\" data-permalink=\"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/mejora_piscinas2\/\" data-orig-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas2.jpg\" data-orig-size=\"2048,1536\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"mejora_piscinas2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas2-1024x768.jpg\" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a href=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas1.jpg\" target=\"_self\"><img decoding=\"async\" width=\"460\" height=\"295\" src=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas1-460x295.jpg\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" data-attachment-id=\"41400\" data-permalink=\"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/mejora_piscinas1\/\" data-orig-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas1.jpg\" data-orig-size=\"2048,1536\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"mejora_piscinas1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas1-1024x768.jpg\" \/><\/a><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":41401,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[544],"tags":[],"class_list":["post-41398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servicios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SERVICIOS | El Ayuntamiento realiza nuevos trabajos de accesibilidad a las instalaciones de la piscina municipal de verano - Ayuntamiento de Mula<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERVICIOS | El Ayuntamiento realiza nuevos trabajos de accesibilidad a las instalaciones de la piscina municipal de verano - Ayuntamiento de Mula\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Mula\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-13T11:55:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas3.jpg?fit=2048%2C945&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"945\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rosario Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@AyuntamientMula\" \/>\n<meta name=\"twitter:site\" content=\"@AyuntamientMula\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosario Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/\"},\"author\":{\"name\":\"Rosario Mart\u00ednez\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/f8d63bd3ab6e7b025268b909b7ab0771\"},\"headline\":\"SERVICIOS | El Ayuntamiento realiza nuevos trabajos de accesibilidad a las instalaciones de la piscina municipal de verano\",\"datePublished\":\"2021-07-13T11:55:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/\"},\"wordCount\":511,\"image\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mejora_piscinas3.jpg\",\"articleSection\":[\"servicios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/\",\"name\":\"SERVICIOS | El Ayuntamiento realiza nuevos trabajos de accesibilidad a las instalaciones de la piscina municipal de verano - Ayuntamiento de Mula\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mejora_piscinas3.jpg\",\"datePublished\":\"2021-07-13T11:55:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/f8d63bd3ab6e7b025268b909b7ab0771\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mejora_piscinas3.jpg\",\"contentUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mejora_piscinas3.jpg\",\"width\":2048,\"height\":945},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mula.es\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERVICIOS | El Ayuntamiento realiza nuevos trabajos de accesibilidad a las instalaciones de la piscina municipal de verano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/\",\"name\":\"Ayuntamiento de Mula\",\"description\":\"P\u00e1gina web del Ayuntamiento de Mula (Regi\u00f3n de Murcia)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mula.es\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/f8d63bd3ab6e7b025268b909b7ab0771\",\"name\":\"Rosario Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g\",\"caption\":\"Rosario Mart\u00ednez\"},\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/author\\\/rmartinez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERVICIOS | El Ayuntamiento realiza nuevos trabajos de accesibilidad a las instalaciones de la piscina municipal de verano - Ayuntamiento de Mula","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/","og_locale":"es_ES","og_type":"article","og_title":"SERVICIOS | El Ayuntamiento realiza nuevos trabajos de accesibilidad a las instalaciones de la piscina municipal de verano - Ayuntamiento de Mula","og_url":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/","og_site_name":"Ayuntamiento de Mula","article_published_time":"2021-07-13T11:55:38+00:00","og_image":[{"width":2048,"height":945,"url":"https:\/\/i0.wp.com\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas3.jpg?fit=2048%2C945&ssl=1","type":"image\/jpeg"}],"author":"Rosario Mart\u00ednez","twitter_card":"summary_large_image","twitter_image":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","twitter_creator":"@AyuntamientMula","twitter_site":"@AyuntamientMula","twitter_misc":{"Escrito por":"Rosario Mart\u00ednez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/#article","isPartOf":{"@id":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/"},"author":{"name":"Rosario Mart\u00ednez","@id":"https:\/\/mula.es\/web\/#\/schema\/person\/f8d63bd3ab6e7b025268b909b7ab0771"},"headline":"SERVICIOS | El Ayuntamiento realiza nuevos trabajos de accesibilidad a las instalaciones de la piscina municipal de verano","datePublished":"2021-07-13T11:55:38+00:00","mainEntityOfPage":{"@id":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/"},"wordCount":511,"image":{"@id":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas3.jpg","articleSection":["servicios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/","url":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/","name":"SERVICIOS | El Ayuntamiento realiza nuevos trabajos de accesibilidad a las instalaciones de la piscina municipal de verano - Ayuntamiento de Mula","isPartOf":{"@id":"https:\/\/mula.es\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/#primaryimage"},"image":{"@id":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas3.jpg","datePublished":"2021-07-13T11:55:38+00:00","author":{"@id":"https:\/\/mula.es\/web\/#\/schema\/person\/f8d63bd3ab6e7b025268b909b7ab0771"},"breadcrumb":{"@id":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/#primaryimage","url":"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas3.jpg","contentUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas3.jpg","width":2048,"height":945},{"@type":"BreadcrumbList","@id":"https:\/\/mula.es\/web\/servicios-el-ayuntamiento-realiza-nuevos-trabajos-de-accesibilidad-a-las-instalaciones-de-la-piscina-municipal-de-verano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mula.es\/web\/"},{"@type":"ListItem","position":2,"name":"SERVICIOS | El Ayuntamiento realiza nuevos trabajos de accesibilidad a las instalaciones de la piscina municipal de verano"}]},{"@type":"WebSite","@id":"https:\/\/mula.es\/web\/#website","url":"https:\/\/mula.es\/web\/","name":"Ayuntamiento de Mula","description":"P\u00e1gina web del Ayuntamiento de Mula (Regi\u00f3n de Murcia)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mula.es\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mula.es\/web\/#\/schema\/person\/f8d63bd3ab6e7b025268b909b7ab0771","name":"Rosario Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g","caption":"Rosario Mart\u00ednez"},"url":"https:\/\/mula.es\/web\/author\/rmartinez\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/07\/mejora_piscinas3.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa9DMY-aLI","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/41398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/comments?post=41398"}],"version-history":[{"count":1,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/41398\/revisions"}],"predecessor-version":[{"id":41402,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/41398\/revisions\/41402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/media\/41401"}],"wp:attachment":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/media?parent=41398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/categories?post=41398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/tags?post=41398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}