{"id":42746,"date":"2021-11-09T11:04:03","date_gmt":"2021-11-09T10:04:03","guid":{"rendered":"https:\/\/mula.es\/web\/?p=42746"},"modified":"2021-11-09T11:04:03","modified_gmt":"2021-11-09T10:04:03","slug":"las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre","status":"publish","type":"post","link":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/","title":{"rendered":"Las obras de rehabilitaci\u00f3n del parque de Bomberos de Mula comenzar\u00e1n a mediados del mes de diciembre"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: justify;\">El alcalde de Mula ha hecho entrega de la licencia de obras al gerente del CEIS<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s de las mejoras en las dependencias del parque, est\u00e1 prevista la adquisici\u00f3n de dos nuevos veh\u00edculos<\/p>\n<p style=\"text-align: justify;\">El alcalde de Mula, Juan Jes\u00fas Moreno, se reune con el gerente del Consorcio de Extinci\u00f3n de Incendios y Salvamento de la Regi\u00f3n de Murcia (CEIS), Francisco Javier Gil, as\u00ed con la secretaria, Ana Garc\u00eda, y el director t\u00e9cnico, Antonio Codina, para hacerles entrega de la licencia de obras del proyecto de rehabilitaci\u00f3n del Parque de Bomberos de Mula.<\/p>\n<p style=\"text-align: justify;\">Dicha licencia asciende a 343.000 euros e incluye el inicio de las obras para mediados del pr\u00f3ximo mes de diciembre con una duraci\u00f3n de aproximadamente ocho meses. El nuevo parque contar\u00e1, adem\u00e1s de con una rehabilitaci\u00f3n integral de las instalaciones, nuevo mobiliario y herramientas, as\u00ed como nuevos veh\u00edculos de extinci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">As\u00ed, el nuevo parque contar\u00e1 con dos nuevos veh\u00edculos, un Bomba Rural Pesada (BRP) con capacidad para 4.000 litros, y un Bomba Nodriza Pesada (BNP) de 8.000 litros, ambos polifuncionales y que cuentan con un presupuesto de m\u00e1s de 500.000 euros.<\/p>\n<p style=\"text-align: justify;\">Las mejoras de estas dependencias fueron aprobadas por la Junta de Gobierno del CEIS del pasado mes julio donde inclu\u00eda en sus presupuestos para 2021 la construcci\u00f3n de un nuevo parque de bomberos en San Pedro del Pinatar y la remodelaci\u00f3n de los parques de Mula, Cieza y La Manga dentro del Plan Estrat\u00e9gico de mejora que la gerencia del Consorcio de Extinci\u00f3n y Salvamento va a llevar a cabo en la Comunidad Aut\u00f3noma.<\/p>\n<p style=\"text-align: justify;\">Juan Jes\u00fas Moreno resaltaba la importancia de que Mula cuente con unas instalaciones y veh\u00edculos apropiados para su labor diaria. \u201cEl parque de Bomberos de Mula da cobertura a los cuatro municipios de la Comarca del R\u00edo Mula y a la parte de Sierra Espu\u00f1a que se encuentra dentro de la misma as\u00ed que, dado a la gran extensi\u00f3n de territorio y la diversidad de espacios es vital que los bomberos cuenten con todas las medidas acorde a la labor que desempe\u00f1an adecuando y modernizando las instalaciones a sus necesidades reales\u201d, explicaba.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><p><a href=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2.jpg\"><img decoding=\"async\" data-attachment-id=\"42748\" data-permalink=\"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/parque_bomberos_2\/\" data-orig-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2.jpg\" data-orig-size=\"2048,1536\" data-comments-opened=\"0\" data-image-meta=\"\" data-image-title=\"parque_bomberos_2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2-1024x768.jpg\" class=\"size-large wp-image-42748 aligncenter\" src=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2-200x150.jpg 200w, https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2-300x225.jpg 300w, https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2-400x300.jpg 400w, https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2-600x450.jpg 600w, https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2-768x576.jpg 768w, https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2-800x600.jpg 800w, https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2-1024x768.jpg 1024w, https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2-1200x900.jpg 1200w, https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_2-1536x1152.jpg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":42747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[770],"tags":[],"class_list":["post-42746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parque-bomberos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las obras de rehabilitaci\u00f3n del parque de Bomberos de Mula comenzar\u00e1n a mediados del mes de diciembre - Ayuntamiento de Mula<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las obras de rehabilitaci\u00f3n del parque de Bomberos de Mula comenzar\u00e1n a mediados del mes de diciembre - Ayuntamiento de Mula\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Mula\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-09T10:04:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_1.jpg?fit=960%2C720&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rosario Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/cropped-escudo-cuadrado.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@AyuntamientMula\" \/>\n<meta name=\"twitter:site\" content=\"@AyuntamientMula\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosario Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/\"},\"author\":{\"name\":\"Rosario Mart\u00ednez\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/f8d63bd3ab6e7b025268b909b7ab0771\"},\"headline\":\"Las obras de rehabilitaci\u00f3n del parque de Bomberos de Mula comenzar\u00e1n a mediados del mes de diciembre\",\"datePublished\":\"2021-11-09T10:04:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/\"},\"wordCount\":1174,\"image\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/parque_bomberos_1.jpg\",\"articleSection\":[\"parque bomberos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/\",\"name\":\"Las obras de rehabilitaci\u00f3n del parque de Bomberos de Mula comenzar\u00e1n a mediados del mes de diciembre - Ayuntamiento de Mula\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/parque_bomberos_1.jpg\",\"datePublished\":\"2021-11-09T10:04:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/f8d63bd3ab6e7b025268b909b7ab0771\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/parque_bomberos_1.jpg\",\"contentUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/parque_bomberos_1.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mula.es\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las obras de rehabilitaci\u00f3n del parque de Bomberos de Mula comenzar\u00e1n a mediados del mes de diciembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/\",\"name\":\"Ayuntamiento de Mula\",\"description\":\"P\u00e1gina web del Ayuntamiento de Mula (Regi\u00f3n de Murcia)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mula.es\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/f8d63bd3ab6e7b025268b909b7ab0771\",\"name\":\"Rosario Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g\",\"caption\":\"Rosario Mart\u00ednez\"},\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/author\\\/rmartinez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las obras de rehabilitaci\u00f3n del parque de Bomberos de Mula comenzar\u00e1n a mediados del mes de diciembre - Ayuntamiento de Mula","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/","og_locale":"es_ES","og_type":"article","og_title":"Las obras de rehabilitaci\u00f3n del parque de Bomberos de Mula comenzar\u00e1n a mediados del mes de diciembre - Ayuntamiento de Mula","og_url":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/","og_site_name":"Ayuntamiento de Mula","article_published_time":"2021-11-09T10:04:03+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/i0.wp.com\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_1.jpg?fit=960%2C720&ssl=1","type":"image\/jpeg"}],"author":"Rosario Mart\u00ednez","twitter_card":"summary_large_image","twitter_image":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/cropped-escudo-cuadrado.jpg","twitter_creator":"@AyuntamientMula","twitter_site":"@AyuntamientMula","twitter_misc":{"Escrito por":"Rosario Mart\u00ednez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/#article","isPartOf":{"@id":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/"},"author":{"name":"Rosario Mart\u00ednez","@id":"https:\/\/mula.es\/web\/#\/schema\/person\/f8d63bd3ab6e7b025268b909b7ab0771"},"headline":"Las obras de rehabilitaci\u00f3n del parque de Bomberos de Mula comenzar\u00e1n a mediados del mes de diciembre","datePublished":"2021-11-09T10:04:03+00:00","mainEntityOfPage":{"@id":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/"},"wordCount":1174,"image":{"@id":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/#primaryimage"},"thumbnailUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_1.jpg","articleSection":["parque bomberos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/","url":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/","name":"Las obras de rehabilitaci\u00f3n del parque de Bomberos de Mula comenzar\u00e1n a mediados del mes de diciembre - Ayuntamiento de Mula","isPartOf":{"@id":"https:\/\/mula.es\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/#primaryimage"},"image":{"@id":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/#primaryimage"},"thumbnailUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_1.jpg","datePublished":"2021-11-09T10:04:03+00:00","author":{"@id":"https:\/\/mula.es\/web\/#\/schema\/person\/f8d63bd3ab6e7b025268b909b7ab0771"},"breadcrumb":{"@id":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/#primaryimage","url":"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_1.jpg","contentUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_1.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/mula.es\/web\/las-obras-de-rehabilitacion-del-parque-de-bomberos-de-mula-comenzaran-a-mediados-del-mes-de-diciembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mula.es\/web\/"},{"@type":"ListItem","position":2,"name":"Las obras de rehabilitaci\u00f3n del parque de Bomberos de Mula comenzar\u00e1n a mediados del mes de diciembre"}]},{"@type":"WebSite","@id":"https:\/\/mula.es\/web\/#website","url":"https:\/\/mula.es\/web\/","name":"Ayuntamiento de Mula","description":"P\u00e1gina web del Ayuntamiento de Mula (Regi\u00f3n de Murcia)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mula.es\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mula.es\/web\/#\/schema\/person\/f8d63bd3ab6e7b025268b909b7ab0771","name":"Rosario Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g","caption":"Rosario Mart\u00ednez"},"url":"https:\/\/mula.es\/web\/author\/rmartinez\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa9DMY-b7s","jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/mula.es\/web\/wp-content\/uploads\/2021\/11\/parque_bomberos_1.jpg","_links":{"self":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/42746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/comments?post=42746"}],"version-history":[{"count":1,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/42746\/revisions"}],"predecessor-version":[{"id":42749,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/42746\/revisions\/42749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/media\/42747"}],"wp:attachment":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/media?parent=42746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/categories?post=42746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/tags?post=42746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}