{"id":44415,"date":"2022-05-12T14:46:20","date_gmt":"2022-05-12T12:46:20","guid":{"rendered":"https:\/\/mula.es\/web\/?p=44415"},"modified":"2022-05-12T14:51:00","modified_gmt":"2022-05-12T12:51:00","slug":"festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas","status":"publish","type":"post","link":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/","title":{"rendered":"FESTEJOS | Fiestas de San Isidro: Concurso de Ornamentaci\u00f3n tradicional de carpas y carrozas"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h2><\/h2>\n<h2 style=\"text-align: center;\"><strong><a href=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2022\/05\/BASES-CONCURSO-CARROZAS-Y-CARPAS.pdf\" target=\"_blank\" rel=\"noopener\">Descarga las bases del Concurso de ornamentaci\u00f3n tradicional de carpas y carrozas (.pdf)<\/a><\/strong><\/h2>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\" style=\"--awb-text-transform:none;\"><h2>BASES<\/h2>\n<p><strong>1 \u2013<\/strong> Podr\u00e1n participar en este concurso, previa inscripci\u00f3n y consentimiento, las carrozas participantes en el Desfile de Carrozas del d\u00eda 14 de mayo de 2022 y las carpas instaladas por el Ayuntamiento de Mula en el recinto ferial durante las fiestas San Isidro 2022.<\/p>\n<p><strong>2 \u2013<\/strong> La participaci\u00f3n en este concurso requiere inscripci\u00f3n previa del siguiente modo:<\/p>\n<ul>\n<li>En el recinto de las pe\u00f1as el jueves 12 de mayo, a instancia de la organizaci\u00f3n.<\/li>\n<li>En el acto de sorteo del orden del Desfile de Carrozas. Jueves 12 de mayo. Centro Joven<\/li>\n<\/ul>\n<p><strong>3 \u2013<\/strong> Datos a aportar: Nombre de la pe\u00f1a\/asociaci\u00f3n, datos del responsable, tel\u00e9fono, correo electr\u00f3nico, nombre de la carroza y\/o carpa, n\u00famero de orden desfile de carrozas, n\u00famero de carpa.<\/p>\n<p><strong>4 \u2013<\/strong> Se valorar\u00e1:<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>La ornamentaci\u00f3n con escenas o elementos huertanos que pongan en valor oficios, vestimentas y folclore relacionados con las fiestas de san Isidro, la huerta y el campo de Mula<\/li>\n<li>La originalidad y calidad est\u00e9tica de la decoraci\u00f3n.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong>5 \u2013 <\/strong>Es impresdible que las carpas participantes permanezcan decoradas el total de d\u00edas de su utilizaci\u00f3n hasta el 15 de mayo. En el caso de las carrozas, se debe realizar todo el recorrido previsto sin abandonar el desfile. En ambos casos se tomar\u00e1n las medidas de seguridad necesarias para garantizar la fijaci\u00f3n de los elementos y el anclaje de estructuras, estando a disposici\u00f3n de los que pueda objetar la organizaci\u00f3n.<\/p>\n<h3>6\u00a0 \u2013 Premios<\/h3>\n<p>Se establecen dos premios:<\/p>\n<p>Mejor carroza 200\u20ac. Ayuntamiento de Mula<\/p>\n<p>Mejor carpa\u00a0\u00a0 200\u20ac. El Plan del Mono<\/p>\n<h3>7\u00a0 \u2013 El Jurado<\/h3>\n<p>El Jurado estar\u00e1 compuesto por personas relacionadas con el mundo de la cultura y el arte.<\/p>\n<ul>\n<li>\u2013 Las fotograf\u00edas que pueda tomar el jurado de las carpas y carrozas participantesquedar\u00e1n en propiedad del Excmo. Ayuntamiento de Mula, que se reserva todos los derechos, pudiendo ser utilizados para publicaciones en folletos y\/o programaciones de promoci\u00f3n tur\u00edstica de nuestra ciudad y municipio.<\/li>\n<li>\u2013 La participaci\u00f3n en este concurso supone la aceptaci\u00f3n de las presentes bases,siendo inapelable el fallo del jurado. La organizaci\u00f3n resolver\u00e1 sobre todas las cuestiones no previstas en estas bases.<\/li>\n<\/ul>\n<h3>PROTECCI\u00d3N DE DATOS<\/h3>\n<p>De conformidad con lo dispuesto en el Reglamento (UE) 2016\/679 relativo a la protecci\u00f3n de los datos personales de las personas f\u00edsicas (RGPD) y Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales. Vd. da su consentimiento para el tratamiento de los datos personales aportados a trav\u00e9s de su inscripci\u00f3n en el <strong>CONCURSO de ORNAMENTACI\u00d3N TRADICIONAL CARPAS Y CARROZAS FIESTAS DE SAN<\/strong><\/p>\n<p><strong>ISIDRO 2022.\u00a0 <\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":32325,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[171],"tags":[382],"class_list":["post-44415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festejos","tag-fiestas-de-san-isidro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FESTEJOS | Fiestas de San Isidro: Concurso de Ornamentaci\u00f3n tradicional de carpas y carrozas - Ayuntamiento de Mula<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FESTEJOS | Fiestas de San Isidro: Concurso de Ornamentaci\u00f3n tradicional de carpas y carrozas - Ayuntamiento de Mula\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Mula\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-12T12:46:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-12T12:51:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/mula.es\/web\/wp-content\/uploads\/2020\/02\/san_isidro_3-scaled.jpg?fit=2560%2C1920&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rosario Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@AyuntamientMula\" \/>\n<meta name=\"twitter:site\" content=\"@AyuntamientMula\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosario Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/\"},\"author\":{\"name\":\"Rosario Mart\u00ednez\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/f8d63bd3ab6e7b025268b909b7ab0771\"},\"headline\":\"FESTEJOS | Fiestas de San Isidro: Concurso de Ornamentaci\u00f3n tradicional de carpas y carrozas\",\"datePublished\":\"2022-05-12T12:46:20+00:00\",\"dateModified\":\"2022-05-12T12:51:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/\"},\"wordCount\":1258,\"image\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/san_isidro_3-scaled.jpg\",\"keywords\":[\"fiestas de san isidro\"],\"articleSection\":[\"festejos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/\",\"name\":\"FESTEJOS | Fiestas de San Isidro: Concurso de Ornamentaci\u00f3n tradicional de carpas y carrozas - Ayuntamiento de Mula\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/san_isidro_3-scaled.jpg\",\"datePublished\":\"2022-05-12T12:46:20+00:00\",\"dateModified\":\"2022-05-12T12:51:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/f8d63bd3ab6e7b025268b909b7ab0771\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/san_isidro_3-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/san_isidro_3-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mula.es\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FESTEJOS | Fiestas de San Isidro: Concurso de Ornamentaci\u00f3n tradicional de carpas y carrozas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/\",\"name\":\"Ayuntamiento de Mula\",\"description\":\"P\u00e1gina web del Ayuntamiento de Mula (Regi\u00f3n de Murcia)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mula.es\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/f8d63bd3ab6e7b025268b909b7ab0771\",\"name\":\"Rosario Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g\",\"caption\":\"Rosario Mart\u00ednez\"},\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/author\\\/rmartinez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FESTEJOS | Fiestas de San Isidro: Concurso de Ornamentaci\u00f3n tradicional de carpas y carrozas - Ayuntamiento de Mula","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/","og_locale":"es_ES","og_type":"article","og_title":"FESTEJOS | Fiestas de San Isidro: Concurso de Ornamentaci\u00f3n tradicional de carpas y carrozas - Ayuntamiento de Mula","og_url":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/","og_site_name":"Ayuntamiento de Mula","article_published_time":"2022-05-12T12:46:20+00:00","article_modified_time":"2022-05-12T12:51:00+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/i0.wp.com\/mula.es\/web\/wp-content\/uploads\/2020\/02\/san_isidro_3-scaled.jpg?fit=2560%2C1920&ssl=1","type":"image\/jpeg"}],"author":"Rosario Mart\u00ednez","twitter_card":"summary_large_image","twitter_image":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","twitter_creator":"@AyuntamientMula","twitter_site":"@AyuntamientMula","twitter_misc":{"Escrito por":"Rosario Mart\u00ednez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/#article","isPartOf":{"@id":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/"},"author":{"name":"Rosario Mart\u00ednez","@id":"https:\/\/mula.es\/web\/#\/schema\/person\/f8d63bd3ab6e7b025268b909b7ab0771"},"headline":"FESTEJOS | Fiestas de San Isidro: Concurso de Ornamentaci\u00f3n tradicional de carpas y carrozas","datePublished":"2022-05-12T12:46:20+00:00","dateModified":"2022-05-12T12:51:00+00:00","mainEntityOfPage":{"@id":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/"},"wordCount":1258,"image":{"@id":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/#primaryimage"},"thumbnailUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/02\/san_isidro_3-scaled.jpg","keywords":["fiestas de san isidro"],"articleSection":["festejos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/","url":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/","name":"FESTEJOS | Fiestas de San Isidro: Concurso de Ornamentaci\u00f3n tradicional de carpas y carrozas - Ayuntamiento de Mula","isPartOf":{"@id":"https:\/\/mula.es\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/#primaryimage"},"image":{"@id":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/#primaryimage"},"thumbnailUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/02\/san_isidro_3-scaled.jpg","datePublished":"2022-05-12T12:46:20+00:00","dateModified":"2022-05-12T12:51:00+00:00","author":{"@id":"https:\/\/mula.es\/web\/#\/schema\/person\/f8d63bd3ab6e7b025268b909b7ab0771"},"breadcrumb":{"@id":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/#primaryimage","url":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/02\/san_isidro_3-scaled.jpg","contentUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/02\/san_isidro_3-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/mula.es\/web\/festejos-fiestas-de-san-isidro-concurso-de-ornamentacion-tradicional-de-carpas-y-carrozas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mula.es\/web\/"},{"@type":"ListItem","position":2,"name":"FESTEJOS | Fiestas de San Isidro: Concurso de Ornamentaci\u00f3n tradicional de carpas y carrozas"}]},{"@type":"WebSite","@id":"https:\/\/mula.es\/web\/#website","url":"https:\/\/mula.es\/web\/","name":"Ayuntamiento de Mula","description":"P\u00e1gina web del Ayuntamiento de Mula (Regi\u00f3n de Murcia)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mula.es\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mula.es\/web\/#\/schema\/person\/f8d63bd3ab6e7b025268b909b7ab0771","name":"Rosario Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce916b980ac93e5b1d36e6068357675d4e089a572ebc8789fcb807c2fb2edfef?s=96&d=mm&r=g","caption":"Rosario Mart\u00ednez"},"url":"https:\/\/mula.es\/web\/author\/rmartinez\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa9DMY-byn","jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/02\/san_isidro_3-scaled.jpg","_links":{"self":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/44415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/comments?post=44415"}],"version-history":[{"count":3,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/44415\/revisions"}],"predecessor-version":[{"id":44420,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/44415\/revisions\/44420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/media\/32325"}],"wp:attachment":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/media?parent=44415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/categories?post=44415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/tags?post=44415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}