{"id":54771,"date":"2024-07-17T13:14:04","date_gmt":"2024-07-17T11:14:04","guid":{"rendered":"https:\/\/mula.es\/web\/?p=54771"},"modified":"2024-07-17T13:14:04","modified_gmt":"2024-07-17T11:14:04","slug":"servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui","status":"publish","type":"post","link":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/","title":{"rendered":"SERVICIOS SOCIALES | Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui"},"content":{"rendered":"<p><strong>Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui<\/strong><\/p>\n<p><strong>Mula, 17 de julio de 2024<\/strong> \u2013 Esta ma\u00f1ana se ha firmado el convenio de colaboraci\u00f3n entre el Ayuntamiento de Mula y la Asociaci\u00f3n Sonrisa Saharaui. En el evento han estado presentes el alcalde, Juan Jes\u00fas Moreno, la presidenta de la Asociaci\u00f3n, Juana Abenza, y la concejala de Pol\u00edtica Social, Antonia Gabarr\u00f3n. Tambi\u00e9n asistieron las cuatro familias de acogida y los cuatro ni\u00f1os saharauis que pasar\u00e1n el verano en Mula.<\/p>\n<p>Este acuerdo formaliza la cooperaci\u00f3n entre ambas entidades para la acogida de ni\u00f1os y ni\u00f1as saharauis en Mula, en el marco del <em>Programa de Acogida Temporal en Verano<\/em>, conocido como \u201cVacaciones en Paz\u201d. Este programa refleja el compromiso del Ayuntamiento de Mula de apoyar iniciativas y asociaciones que promuevan el respeto a los derechos humanos y que ofrezcan ayuda a personas y colectivos en situaci\u00f3n de vulnerabilidad en pa\u00edses desfavorecidos, con los cuales compartimos lazos hist\u00f3ricos y culturales.<\/p>\n<p>Durante la firma, el alcalde Juan Jes\u00fas Moreno expres\u00f3: <em>\u201cEste convenio es una muestra de nuestra solidaridad y compromiso con el pueblo saharaui. Invito a las familias mule\u00f1as a participar activamente en este programa y a brindar su apoyo a estos ni\u00f1os que tanto lo necesitan\u201d.<\/em><\/p>\n<p>Por su parte, Juana Abenza, presidenta de la Asociaci\u00f3n Sonrisa Saharaui, destac\u00f3: <em>\u201cAgradecemos al Ayuntamiento de Mula y a las familias de acogida por su generosidad y por abrir sus hogares a estos ni\u00f1os. Este programa no solo ofrece un respiro a los ni\u00f1os saharauis, sino que tambi\u00e9n fortalece los lazos de amistad y solidaridad entre nuestros pueblos\u201d.<\/em><\/p>\n<p>El Ayuntamiento de Mula anima a todos los ciudadanos a involucrarse en este programa y a contribuir a la creaci\u00f3n de un entorno acogedor y solidario para los ni\u00f1os saharauis durante su estancia en nuestra ciudad.<\/p>\n<p><a href=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13.jpg\"><img decoding=\"async\" data-attachment-id=\"54772\" data-permalink=\"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/1-80\/\" data-orig-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13.jpg\" data-orig-size=\"1080,1080\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13-1024x1024.jpg\" class=\"alignnone size-medium wp-image-54772\" src=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13-66x66.jpg 66w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13-150x150.jpg 150w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13-200x200.jpg 200w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13-300x300.jpg 300w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13-400x400.jpg 400w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13-600x600.jpg 600w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13-768x768.jpg 768w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13-800x800.jpg 800w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13-1024x1024.jpg 1024w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/1-13.jpg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12.jpg\"><img decoding=\"async\" data-attachment-id=\"54773\" data-permalink=\"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/2-74\/\" data-orig-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12.jpg\" data-orig-size=\"1080,1080\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12-1024x1024.jpg\" class=\"alignnone size-medium wp-image-54773\" src=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12-66x66.jpg 66w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12-150x150.jpg 150w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12-200x200.jpg 200w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12-300x300.jpg 300w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12-400x400.jpg 400w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12-600x600.jpg 600w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12-768x768.jpg 768w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12-800x800.jpg 800w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12-1024x1024.jpg 1024w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/2-12.jpg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10.jpg\"><img decoding=\"async\" data-attachment-id=\"54774\" data-permalink=\"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/3-66\/\" data-orig-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10.jpg\" data-orig-size=\"1080,1080\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10-1024x1024.jpg\" class=\"alignnone size-medium wp-image-54774\" src=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10-66x66.jpg 66w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10-150x150.jpg 150w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10-200x200.jpg 200w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10-300x300.jpg 300w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10-400x400.jpg 400w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10-600x600.jpg 600w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10-768x768.jpg 768w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10-800x800.jpg 800w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10-1024x1024.jpg 1024w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/3-10.jpg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7.jpg\"><img decoding=\"async\" data-attachment-id=\"54775\" data-permalink=\"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/4-47\/\" data-orig-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7.jpg\" data-orig-size=\"1080,1080\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"4\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7-1024x1024.jpg\" class=\"alignnone size-medium wp-image-54775\" src=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7-66x66.jpg 66w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7-150x150.jpg 150w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7-200x200.jpg 200w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7-300x300.jpg 300w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7-400x400.jpg 400w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7-600x600.jpg 600w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7-768x768.jpg 768w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7-800x800.jpg 800w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7-1024x1024.jpg 1024w, https:\/\/mula.es\/web\/wp-content\/uploads\/2024\/07\/4-7.jpg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui Mula, 17 de julio de 2024 \u2013 Esta ma\u00f1ana se ha firmado el convenio de colaboraci\u00f3n entre el Ayuntamiento de Mula y la Asociaci\u00f3n Sonrisa Saharaui. En el evento han estado presentes el alcalde, Juan Jes\u00fas Moreno, la presidenta de la Asociaci\u00f3n, Juana Abenza, y  [&#8230;]<\/p>\n","protected":false},"author":13,"featured_media":33512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[418,338,93],"tags":[],"class_list":["post-54771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intedis","category-obras-y-servicios","category-servicios-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SERVICIOS SOCIALES | Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui - Ayuntamiento de Mula<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERVICIOS SOCIALES | Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui - Ayuntamiento de Mula\" \/>\n<meta property=\"og:description\" content=\"Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui Mula, 17 de julio de 2024 \u2013 Esta ma\u00f1ana se ha firmado el convenio de colaboraci\u00f3n entre el Ayuntamiento de Mula y la Asociaci\u00f3n Sonrisa Saharaui. En el evento han estado presentes el alcalde, Juan Jes\u00fas Moreno, la presidenta de la Asociaci\u00f3n, Juana Abenza, y [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Mula\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-17T11:14:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"218\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura Salas Orcajada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AyuntamientMula\" \/>\n<meta name=\"twitter:site\" content=\"@AyuntamientMula\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura Salas Orcajada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/\"},\"author\":{\"name\":\"Laura Salas Orcajada\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/4f10179bd364f40dceed361e61e4033f\"},\"headline\":\"SERVICIOS SOCIALES | Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui\",\"datePublished\":\"2024-07-17T11:14:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/\"},\"wordCount\":336,\"image\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/escudo-cuadrado-e1591045058235.jpg\",\"articleSection\":[\"intedis\",\"obras y servicios\",\"servicios sociales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/\",\"name\":\"SERVICIOS SOCIALES | Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui - Ayuntamiento de Mula\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/escudo-cuadrado-e1591045058235.jpg\",\"datePublished\":\"2024-07-17T11:14:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/4f10179bd364f40dceed361e61e4033f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/escudo-cuadrado-e1591045058235.jpg\",\"contentUrl\":\"https:\\\/\\\/mula.es\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/escudo-cuadrado-e1591045058235.jpg\",\"width\":200,\"height\":218},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mula.es\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERVICIOS SOCIALES | Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/\",\"name\":\"Ayuntamiento de Mula\",\"description\":\"P\u00e1gina web del Ayuntamiento de Mula (Regi\u00f3n de Murcia)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mula.es\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mula.es\\\/web\\\/#\\\/schema\\\/person\\\/4f10179bd364f40dceed361e61e4033f\",\"name\":\"Laura Salas Orcajada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/786f2a223d9a455e2a448f78b5dcc1117207ef56ef3d9a04df338c0f775cd403?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/786f2a223d9a455e2a448f78b5dcc1117207ef56ef3d9a04df338c0f775cd403?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/786f2a223d9a455e2a448f78b5dcc1117207ef56ef3d9a04df338c0f775cd403?s=96&d=mm&r=g\",\"caption\":\"Laura Salas Orcajada\"},\"url\":\"https:\\\/\\\/mula.es\\\/web\\\/author\\\/lsalas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERVICIOS SOCIALES | Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui - Ayuntamiento de Mula","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/","og_locale":"es_ES","og_type":"article","og_title":"SERVICIOS SOCIALES | Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui - Ayuntamiento de Mula","og_description":"Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui Mula, 17 de julio de 2024 \u2013 Esta ma\u00f1ana se ha firmado el convenio de colaboraci\u00f3n entre el Ayuntamiento de Mula y la Asociaci\u00f3n Sonrisa Saharaui. En el evento han estado presentes el alcalde, Juan Jes\u00fas Moreno, la presidenta de la Asociaci\u00f3n, Juana Abenza, y [...]","og_url":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/","og_site_name":"Ayuntamiento de Mula","article_published_time":"2024-07-17T11:14:04+00:00","og_image":[{"width":200,"height":218,"url":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","type":"image\/jpeg"}],"author":"Laura Salas Orcajada","twitter_card":"summary_large_image","twitter_creator":"@AyuntamientMula","twitter_site":"@AyuntamientMula","twitter_misc":{"Escrito por":"Laura Salas Orcajada","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/#article","isPartOf":{"@id":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/"},"author":{"name":"Laura Salas Orcajada","@id":"https:\/\/mula.es\/web\/#\/schema\/person\/4f10179bd364f40dceed361e61e4033f"},"headline":"SERVICIOS SOCIALES | Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui","datePublished":"2024-07-17T11:14:04+00:00","mainEntityOfPage":{"@id":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/"},"wordCount":336,"image":{"@id":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/#primaryimage"},"thumbnailUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","articleSection":["intedis","obras y servicios","servicios sociales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/","url":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/","name":"SERVICIOS SOCIALES | Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui - Ayuntamiento de Mula","isPartOf":{"@id":"https:\/\/mula.es\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/#primaryimage"},"image":{"@id":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/#primaryimage"},"thumbnailUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","datePublished":"2024-07-17T11:14:04+00:00","author":{"@id":"https:\/\/mula.es\/web\/#\/schema\/person\/4f10179bd364f40dceed361e61e4033f"},"breadcrumb":{"@id":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/#primaryimage","url":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","contentUrl":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","width":200,"height":218},{"@type":"BreadcrumbList","@id":"https:\/\/mula.es\/web\/servicios-sociales-firma-del-convenio-de-colaboracion-con-la-asociacion-sonrisa-saharaui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mula.es\/web\/"},{"@type":"ListItem","position":2,"name":"SERVICIOS SOCIALES | Firma del convenio de colaboraci\u00f3n con la Asociaci\u00f3n Sonrisa Saharaui"}]},{"@type":"WebSite","@id":"https:\/\/mula.es\/web\/#website","url":"https:\/\/mula.es\/web\/","name":"Ayuntamiento de Mula","description":"P\u00e1gina web del Ayuntamiento de Mula (Regi\u00f3n de Murcia)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mula.es\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mula.es\/web\/#\/schema\/person\/4f10179bd364f40dceed361e61e4033f","name":"Laura Salas Orcajada","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/786f2a223d9a455e2a448f78b5dcc1117207ef56ef3d9a04df338c0f775cd403?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/786f2a223d9a455e2a448f78b5dcc1117207ef56ef3d9a04df338c0f775cd403?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/786f2a223d9a455e2a448f78b5dcc1117207ef56ef3d9a04df338c0f775cd403?s=96&d=mm&r=g","caption":"Laura Salas Orcajada"},"url":"https:\/\/mula.es\/web\/author\/lsalas\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/mula.es\/web\/wp-content\/uploads\/2020\/06\/escudo-cuadrado-e1591045058235.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa9DMY-efp","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/54771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/comments?post=54771"}],"version-history":[{"count":1,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/54771\/revisions"}],"predecessor-version":[{"id":54776,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/posts\/54771\/revisions\/54776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/media\/33512"}],"wp:attachment":[{"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/media?parent=54771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/categories?post=54771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mula.es\/web\/wp-json\/wp\/v2\/tags?post=54771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}